{"id":5778,"date":"2016-04-03T09:04:13","date_gmt":"2016-04-03T09:04:13","guid":{"rendered":"http:\/\/www.brettspielwelt.de\/Magazin\/?p=5778"},"modified":"2017-10-31T10:08:19","modified_gmt":"2017-10-31T10:08:19","slug":"rezension-quadropolis","status":"publish","type":"post","link":"https:\/\/www.brettspielwelt.de\/Magazin\/rezension-quadropolis\/","title":{"rendered":"Rezension Quadropolis"},"content":{"rendered":"<p>In Quadropolis von Asmodee bauen vier Baumeister auf ihren eigenen Pl\u00e4nen ihre pers\u00f6nliche Traumstadt. Das quietschbunte, futuristische Design l\u00e4sst leicht den Eindruck aufkommen, dass es sich hier um ein Kinder- oder Spa\u00dfspiel handelt &#8211; aber weit gefehlt. Quadropolis ist ein knallhartes Strategiespiel, in dem man ohne konkreten Plan gegen pfiffige Gegner kaum eine Chance haben wird. Damit der Einstieg nicht zu schwierig wird, gibt es allerdings eine reduzierte Anf\u00e4ngervariante, von der man sich aus zur &#8222;Profiregel&#8220; hochspielen kann.<a href=\"https:\/\/www.brettspielwelt.de\/Magazin\/rezension-quadropolis\/quadropolis-packshot\/\" rel=\"attachment wp-att-5780\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5780\" src=\"https:\/\/www.brettspielwelt.de\/Magazin\/wp-content\/uploads\/2016\/04\/Quadropolis-Packshot.jpg\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/www.brettspielwelt.de\/Magazin\/wp-content\/uploads\/2016\/04\/Quadropolis-Packshot.jpg 1024w, https:\/\/www.brettspielwelt.de\/Magazin\/wp-content\/uploads\/2016\/04\/Quadropolis-Packshot-300x300.jpg 300w, https:\/\/www.brettspielwelt.de\/Magazin\/wp-content\/uploads\/2016\/04\/Quadropolis-Packshot-620x620.jpg 620w, https:\/\/www.brettspielwelt.de\/Magazin\/wp-content\/uploads\/2016\/04\/Quadropolis-Packshot-768x768.jpg 768w, https:\/\/www.brettspielwelt.de\/Magazin\/wp-content\/uploads\/2016\/04\/Quadropolis-Packshot-940x940.jpg 940w, https:\/\/www.brettspielwelt.de\/Magazin\/wp-content\/uploads\/2016\/04\/Quadropolis-Packshot-100x100.jpg 100w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n<p>Die Zugmechanik ist eigentlich ganz einfach: man w\u00e4hlt einen der offenausliegenden Architekten. Diese verf\u00fcgen \u00fcber eine Zahl zwischen 1-5. Je nach gew\u00e4hlter Zahl darf man von einem offenen Plan an Geb\u00e4udepl\u00e4ttchen entweder in der Spalte oder Zeile mit der entsprechenden Nummer das dort liegende Pl\u00e4ttchen an sich nehmen.<\/p>\n<p>Jede der im Spiel vorhandenen Pl\u00e4ttchenarten hat allerdings eigene Wertungsarten, Bauarten und Funktionen. Meist wird der Spieler also ein ganz bestimmtes Pl\u00e4ttchen haben wollen. Der Clou an der Sache ist, dass die zuvor verwendete Architektenzahl auch beeinflusst, wohin man das Pl\u00e4ttchen legen darf, sodass eventuell das richtige Pl\u00e4ttchen ausliegen k\u00f6nnte, man es aber nicht sinnvoll anlegen kann. Hier ist also Improvisation gefragt.<\/p>\n<p>Nach einer festgelegten Anzahl Runden endet das Spiel und die Wertung beginnt. Jetzt m\u00fcssen Geb\u00e4ude mit Arbeitern und Energie versorgt werden &#8211; allerdings darf man von diesen auch nicht zu viel haben, sonst gibt es Punktabz\u00fcge. Pluspunkte bekommt man hingegen durch die Kombination der vielf\u00e4ltigen Punktepl\u00e4ttchen.<\/p>\n<p>Interessant ist auch, dass manche Pl\u00e4ttchen gestapelt werden k\u00f6nnen. Man hat also die Wahl zwischen dem Bau von T\u00fcrmen oder sich auf dem Spielplan breit zu machen. Nat\u00fcrlich wird es h\u00e4ufig auf eine Mischung darauf hinauslaufen.<\/p>\n<p>Da das Spiel sehr mathematisch entworfen ist, ergibt sich daraus naturgem\u00e4\u00df auch einen optimalen Aufbau der eigenen Stadt &#8211; quasi eine optimale L\u00f6sung. Dies w\u00e4re eine eklatante Schw\u00e4che, wenn man diese L\u00f6sung zuverl\u00e4ssig reproduzieren k\u00f6nnte. Das ist zum Gl\u00fcck nicht der Fall. Schlie\u00dflich konkurrieren die Spieler um die gleichen Pl\u00e4ttchen und sind den gleichen Timing-Zw\u00e4ngen unterworfen. Es gewinnt der, der innerhalb seines Planes am besten improvisieren kann. Denn ohne Improvisation scheitert selbst der beste Plan mit Pauken und Trompeten.<\/p>\n<p>Doch trotz aller Farbvielfalt und der hohen Interaktion sollten potenzielle Spieler sich bewusst sein, dass Quadropolis recht abstrakt ist und f\u00fcr Spa\u00dfspieler auch anstrengend sein kann.\u00a0 Wer hingegen knallhart planen und anschlie\u00dfend seine Pl\u00e4ne immer wieder an die Gegebenheiten anpassen will, der wird mit Quadropolis sicherlich Spa\u00df haben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Quadropolis von Asmodee bauen vier Baumeister auf ihren eigenen Pl\u00e4nen ihre pers\u00f6nliche Traumstadt. Das quietschbunte, futuristische Design l\u00e4sst leicht den Eindruck aufkommen, dass es sich hier um ein Kinder- oder Spa\u00dfspiel handelt &#8211; aber weit gefehlt. Quadropolis ist ein knallhartes Strategiespiel, in dem man ohne konkreten Plan gegen pfiffige Gegner kaum eine Chance haben &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.brettspielwelt.de\/Magazin\/rezension-quadropolis\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eRezension Quadropolis\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1,9],"tags":[241,467],"class_list":["post-5778","post","type-post","status-publish","format-standard","hentry","category-allgemeines","category-spielbesprechung","tag-asmodee","tag-rezension"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/posts\/5778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/comments?post=5778"}],"version-history":[{"count":8,"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/posts\/5778\/revisions"}],"predecessor-version":[{"id":5787,"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/posts\/5778\/revisions\/5787"}],"wp:attachment":[{"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/media?parent=5778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/categories?post=5778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brettspielwelt.de\/Magazin\/wp-json\/wp\/v2\/tags?post=5778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}